{"id":25,"date":"2026-01-07T16:26:16","date_gmt":"2026-01-07T15:26:16","guid":{"rendered":"https:\/\/iscpif.fr\/cobcod\/?page_id=25"},"modified":"2026-02-03T16:22:19","modified_gmt":"2026-02-03T15:22:19","slug":"outcomes","status":"publish","type":"page","link":"https:\/\/iscpif.fr\/cobcod\/outcomes\/","title":{"rendered":"Outcomes"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-mk45zh48-ef79c93ffd04a45984ba312070f591b8\">\n#top .av-special-heading.av-mk45zh48-ef79c93ffd04a45984ba312070f591b8{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-mk45zh48-ef79c93ffd04a45984ba312070f591b8 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-mk45zh48-ef79c93ffd04a45984ba312070f591b8 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-mk45zh48-ef79c93ffd04a45984ba312070f591b8 av-special-heading-h1  avia-builder-el-0  el_before_av_slideshow_full  avia-builder-el-no-sibling '><h1 class='av-special-heading-tag '  itemprop=\"headline\"  >Outcomes<\/h1><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='full_slider_1'  class='avia-fullwidth-slider main_color avia-shadow   avia-builder-el-1  el_after_av_heading  el_before_av_one_full   slider-not-first container_wrap sidebar_right'  ><div  class='avia-slideshow av-1hlf1-dc979b0897605d8a32fb9247615c170e avia-slideshow-featured av_slideshow_full avia-slide-slider av-slideshow-ui av-control-default av-slideshow-manual av-loop-once av-loop-manual-endless av-default-height-applied   avia-slideshow-1' data-slideshow-options=\"{&quot;animation&quot;:&quot;slide&quot;,&quot;autoplay&quot;:false,&quot;loop_autoplay&quot;:&quot;once&quot;,&quot;interval&quot;:5,&quot;loop_manual&quot;:&quot;manual-endless&quot;,&quot;autoplay_stopper&quot;:false,&quot;noNavigation&quot;:false,&quot;bg_slider&quot;:false,&quot;keep_padding&quot;:false,&quot;hoverpause&quot;:false,&quot;show_slide_delay&quot;:0}\"  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><ul class='avia-slideshow-inner ' style='padding-bottom: 21.428571428571%;'><li  class='avia-slideshow-slide av-1hlf1-dc979b0897605d8a32fb9247615c170e__0  av-single-slide slide-1 slide-odd'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-71 avia-img-lazy-loading-not-71\"  src=\"https:\/\/iscpif.fr\/cobcod\/wp-content\/uploads\/sites\/38\/2026\/01\/banner-cobcod.jpg\" width=\"1400\" height=\"300\" title='banner cobcod' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/iscpif.fr\/cobcod\/wp-content\/uploads\/sites\/38\/2026\/01\/banner-cobcod.jpg 1400w, https:\/\/iscpif.fr\/cobcod\/wp-content\/uploads\/sites\/38\/2026\/01\/banner-cobcod-300x64.jpg 300w, https:\/\/iscpif.fr\/cobcod\/wp-content\/uploads\/sites\/38\/2026\/01\/banner-cobcod-1030x221.jpg 1030w, https:\/\/iscpif.fr\/cobcod\/wp-content\/uploads\/sites\/38\/2026\/01\/banner-cobcod-768x165.jpg 768w, https:\/\/iscpif.fr\/cobcod\/wp-content\/uploads\/sites\/38\/2026\/01\/banner-cobcod-705x151.jpg 705w\" sizes=\"(max-width: 1400px) 100vw, 1400px\" \/><\/div><\/li><\/ul><\/div><\/div><div id='after_full_slider_1'  class='main_color av_default_container_wrap container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-25'><div class='entry-content-wrapper clearfix'>\n<div  class='flex_column av-av_one_full-2d22dc0500e159f2b39fe7a147caf14c av_one_full  avia-builder-el-2  el_after_av_slideshow_full  avia-builder-el-no-sibling  first flex_column_div  '     ><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":136,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-25","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/iscpif.fr\/cobcod\/wp-json\/wp\/v2\/pages\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iscpif.fr\/cobcod\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/iscpif.fr\/cobcod\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/iscpif.fr\/cobcod\/wp-json\/wp\/v2\/users\/136"}],"replies":[{"embeddable":true,"href":"https:\/\/iscpif.fr\/cobcod\/wp-json\/wp\/v2\/comments?post=25"}],"version-history":[{"count":4,"href":"https:\/\/iscpif.fr\/cobcod\/wp-json\/wp\/v2\/pages\/25\/revisions"}],"predecessor-version":[{"id":106,"href":"https:\/\/iscpif.fr\/cobcod\/wp-json\/wp\/v2\/pages\/25\/revisions\/106"}],"wp:attachment":[{"href":"https:\/\/iscpif.fr\/cobcod\/wp-json\/wp\/v2\/media?parent=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}